{"id":57958,"date":"2024-04-17T21:56:50","date_gmt":"2024-04-17T19:56:50","guid":{"rendered":"https:\/\/www.schiebener.net\/wordpress\/?p=57958"},"modified":"2024-04-17T21:56:50","modified_gmt":"2024-04-17T19:56:50","slug":"eintritt-frei-vortrag-kneipensterben-und-bierkonsum","status":"publish","type":"post","link":"https:\/\/www.schiebener.net\/wordpress\/eintritt-frei-vortrag-kneipensterben-und-bierkonsum\/","title":{"rendered":"Eintritt frei: Vortrag \u201eKneipensterben und Bierkonsum\u201c"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\"><strong>Dienstag, den 23. April 2024 um 18 Uhr im Blauen Haus des Sauerland-Museums<\/strong><\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/www.schiebener.net\/wordpress\/wp-content\/uploads\/2024\/04\/20240417DorfkneipeDuedinghausenKlein.jpg\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"745\" src=\"https:\/\/www.schiebener.net\/wordpress\/wp-content\/uploads\/2024\/04\/20240417DorfkneipeDuedinghausenKlein.jpg\" alt=\"\" class=\"wp-image-57959\" srcset=\"https:\/\/www.schiebener.net\/wordpress\/wp-content\/uploads\/2024\/04\/20240417DorfkneipeDuedinghausenKlein.jpg 1024w, https:\/\/www.schiebener.net\/wordpress\/wp-content\/uploads\/2024\/04\/20240417DorfkneipeDuedinghausenKlein-300x218.jpg 300w, https:\/\/www.schiebener.net\/wordpress\/wp-content\/uploads\/2024\/04\/20240417DorfkneipeDuedinghausenKlein-768x559.jpg 768w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/a><figcaption class=\"wp-element-caption\">In den Sauerl\u00e4nder Kneipen ging es in der 50er Jahren hoch her, hier im Gasthof  Zur Post in D\u00fcdinghausen (Bild: Dorfarchiv D\u00fcdinghausen)<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>Das \u201eKneipensterben\u201c ist erneut seit der Corona-Pandemie ein medial breit rezipiertes Thema, doch die Verlustangst ist nicht neu: Sp\u00e4testens seit den 1980er Jahren gibt es immer weniger klassische Kneipen. Zeitgleich nehmen der Alkohol- und damit auch der Bierkonsum in Deutschland ab, die Diversit\u00e4t von Getr\u00e4nken jedoch nimmt stark zu.<\/strong><\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Der Vortrag beschreibt die Entwicklung von Kneipen als Sozial- und Trinkr\u00e4umen seit Mitte des 19. Jahrhunderts und blickt dabei vor allem auf Westfalen in den letzten 50 Jahren. Es wird diskutiert, welche Bedeutung und Funktion Kneipen im Alltag ihrer G\u00e4ste hatten und wie sich das Verschwinden der R\u00e4ume erkl\u00e4ren l\u00e4sst. Neben den G\u00e4sten werden die Wirtinnen, Wirte, Kellnerinnen und Kellner in den Blick genommen und ihre Bedeutungen f\u00fcr das soziale Miteinander dargestellt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Die Referentin Dr. Mareen Heying<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dr. Mareen Heying studierte Geschichte, Gender Studies und Philosophie in Bochum, D\u00fcsseldorf und Bologna und wurde 2017 in Bochum und Bologna promoviert. Als wissenschaftliche Mitarbeiterin war sie drei Jahre am <em>Lehrgebiet Geschichte der Europ\u00e4ischen Moderne<\/em> an der FernUniversit\u00e4t in Hagen und zwei Jahre am <em>Lehrstuhl f\u00fcr Neuere und Neueste Geschichte<\/em> an der Heinrich-Heine-Universit\u00e4t D\u00fcsseldorf besch\u00e4ftigt. Sie war als Gastwissenschaftlerin an der Universit\u00e4t von Padova und hat Fellowships&nbsp;in Delhi und am <em>Deutschen Historischen Institut<\/em> in Rom wahrgenommen. Aktuell arbeitet sie als wissenschaftliche Referentin am LWL-Institut f\u00fcr westf\u00e4lische Regionalgeschichte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Vortrag findet am <strong>Dienstag, den 23. April 2024 um 18 Uhr im Blauen Haus des Sauerland-Museums<\/strong> (Alter Markt 30) statt. <strong>Der Eintritt ist frei.<\/strong><br \/><br \/>Weitere Informationen und Anmeldungen telefonisch unter 02931\/94-4444, per E-Mail an <a href=\"mailto:sauerlandmuseum@hochsauerlandkreis.de\">sauerlandmuseum@hochsauerlandkreis.de<\/a> oder auf der Homepage <a href=\"http:\/\/www.sauerland-museum.de\" target=\"_blank\" rel=\"noreferrer noopener\">www.sauerland-museum.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dienstag, den 23. April 2024 um 18 Uhr im Blauen Haus des Sauerland-Museums Das \u201eKneipensterben\u201c ist erneut seit der Corona-Pandemie ein medial breit rezipiertes Thema, doch die Verlustangst ist nicht &hellip; <a href=\"https:\/\/www.schiebener.net\/wordpress\/eintritt-frei-vortrag-kneipensterben-und-bierkonsum\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eEintritt frei: Vortrag \u201eKneipensterben und Bierkonsum\u201c\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[319,7088,303,674,80,1043,4761],"tags":[2962,4677],"class_list":["post-57958","post","type-post","status-publish","format-standard","hentry","category-geschichte","category-gesundheit","category-in-unserem-briefkasten","category-kultur","category-lokales","category-pressemitteilungen","category-soziales","tag-kneipen","tag-sauerland-museum"],"_links":{"self":[{"href":"https:\/\/www.schiebener.net\/wordpress\/wp-json\/wp\/v2\/posts\/57958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schiebener.net\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schiebener.net\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schiebener.net\/wordpress\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schiebener.net\/wordpress\/wp-json\/wp\/v2\/comments?post=57958"}],"version-history":[{"count":0,"href":"https:\/\/www.schiebener.net\/wordpress\/wp-json\/wp\/v2\/posts\/57958\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.schiebener.net\/wordpress\/wp-json\/wp\/v2\/media?parent=57958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schiebener.net\/wordpress\/wp-json\/wp\/v2\/categories?post=57958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schiebener.net\/wordpress\/wp-json\/wp\/v2\/tags?post=57958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}