{"id":48805,"date":"2021-05-06T19:12:56","date_gmt":"2021-05-06T18:12:56","guid":{"rendered":"https:\/\/www.schiebener.net\/wordpress\/?p=48805"},"modified":"2021-05-06T19:12:56","modified_gmt":"2021-05-06T18:12:56","slug":"covid-19-licht-am-ende-des-tunnels-ein-kleiner-kommentar","status":"publish","type":"post","link":"https:\/\/www.schiebener.net\/wordpress\/covid-19-licht-am-ende-des-tunnels-ein-kleiner-kommentar\/","title":{"rendered":"COVID-19: Licht am Ende des Tunnels? Ein kleiner Kommentar."},"content":{"rendered":"<figure id=\"attachment_48806\" aria-describedby=\"caption-attachment-48806\" style=\"width: 700px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.schiebener.net\/wordpress\/wp-content\/uploads\/2021\/05\/2021050401Fledermaustunnel.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-48806\" src=\"https:\/\/www.schiebener.net\/wordpress\/wp-content\/uploads\/2021\/05\/2021050401Fledermaustunnel.jpg\" alt=\"\" width=\"700\" height=\"470\" srcset=\"https:\/\/www.schiebener.net\/wordpress\/wp-content\/uploads\/2021\/05\/2021050401Fledermaustunnel.jpg 2048w, https:\/\/www.schiebener.net\/wordpress\/wp-content\/uploads\/2021\/05\/2021050401Fledermaustunnel-300x201.jpg 300w, https:\/\/www.schiebener.net\/wordpress\/wp-content\/uploads\/2021\/05\/2021050401Fledermaustunnel-1024x687.jpg 1024w, https:\/\/www.schiebener.net\/wordpress\/wp-content\/uploads\/2021\/05\/2021050401Fledermaustunnel-768x515.jpg 768w, https:\/\/www.schiebener.net\/wordpress\/wp-content\/uploads\/2021\/05\/2021050401Fledermaustunnel-1536x1031.jpg 1536w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-48806\" class=\"wp-caption-text\">Licht am Ende des Fledermaustunnels bei Bromskirchen. (foto: zoom)<\/figcaption><\/figure>\n<p><strong>Die dritte Welle scheint gebrochen, die Zahl der Neuinfektionen und damit die Sieben-Tage-Inzidenzen sinken merklich.<\/strong><\/p>\n<p>Noch sind wir von der &#8222;Trauminzidenz&#8220; &lt; 10 weit entfernt. Die Zahl der t\u00e4glichen Covid-19-Todesf\u00e4lle ist nicht erfreulich. Die Impfkampagne kommt zwar in Schwung, aber Kinder und Jugendliche, die sich wieder mehr und mehr in gro\u00dfen Kohorten in den KiTas und Schulen einfinden, m\u00fcssen sich hinten anstellen. Das Image von AstraZeneca ist kaputt.<\/p>\n<p>Es wird mehr \u00fcber Lockerungen, \u00d6ffnungen und Urlaub gesprochen und geschrieben als \u00fcber die Gefahren von Long Covid.<\/p>\n<p>Ja, es ist Licht am Ende des Tunnels zu sehen. Je schneller wir die Inzidenzen dr\u00fccken, desto weniger Menschen m\u00fcssen noch sterben oder an den Folgesch\u00e4den einer COVID-19-Erkrankung leiden.<\/p>\n<p>Und dann sollten wir bei aller Urlaubseuphorie nicht vergessen, dass wir es mit einer weltweiten Pandemie zu tun haben. Wenn wir jetzt Fehler machen und uns in eine Lockerungswelle hineinsteigern, k\u00f6nnten wir das noch vor dem Tunnelausgang bereuen. Das Virus erlaubt keine Wunschkonzerte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die dritte Welle scheint gebrochen, die Zahl der Neuinfektionen und damit die Sieben-Tage-Inzidenzen sinken merklich. Noch sind wir von der &#8222;Trauminzidenz&#8220; &lt; 10 weit entfernt. Die Zahl der t\u00e4glichen Covid-19-Todesf\u00e4lle &hellip; <a href=\"https:\/\/www.schiebener.net\/wordpress\/covid-19-licht-am-ende-des-tunnels-ein-kleiner-kommentar\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eCOVID-19: Licht am Ende des Tunnels? Ein kleiner Kommentar.\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7088],"tags":[8580,8610],"class_list":["post-48805","post","type-post","status-publish","format-standard","hentry","category-gesundheit","tag-covid-19","tag-pandemie"],"_links":{"self":[{"href":"https:\/\/www.schiebener.net\/wordpress\/wp-json\/wp\/v2\/posts\/48805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schiebener.net\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schiebener.net\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schiebener.net\/wordpress\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schiebener.net\/wordpress\/wp-json\/wp\/v2\/comments?post=48805"}],"version-history":[{"count":0,"href":"https:\/\/www.schiebener.net\/wordpress\/wp-json\/wp\/v2\/posts\/48805\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.schiebener.net\/wordpress\/wp-json\/wp\/v2\/media?parent=48805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schiebener.net\/wordpress\/wp-json\/wp\/v2\/categories?post=48805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schiebener.net\/wordpress\/wp-json\/wp\/v2\/tags?post=48805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}