{"id":33927,"date":"2015-11-10T22:27:49","date_gmt":"2015-11-10T21:27:49","guid":{"rendered":"http:\/\/www.schiebener.net\/wordpress\/?p=33927"},"modified":"2015-11-11T06:02:07","modified_gmt":"2015-11-11T05:02:07","slug":"r-i-p-helmut-schmidt-23-dezember-1918-in-hamburg-%e2%80%a0-10-november-2015-ebenda","status":"publish","type":"post","link":"https:\/\/www.schiebener.net\/wordpress\/r-i-p-helmut-schmidt-23-dezember-1918-in-hamburg-%e2%80%a0-10-november-2015-ebenda\/","title":{"rendered":"R.I.P. Helmut Schmidt (* 23. Dezember 1918 in Hamburg; \u2020 10. November 2015 ebenda)"},"content":{"rendered":"<figure id=\"attachment_33929\" aria-describedby=\"caption-attachment-33929\" style=\"width: 686px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.schiebener.net\/wordpress\/wp-content\/uploads\/2015\/11\/helmutschmidt.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-33929\" src=\"http:\/\/www.schiebener.net\/wordpress\/wp-content\/uploads\/2015\/11\/helmutschmidt.jpg\" alt=\"Helmut Schmidt auf einem Parteitag der SPD in Dortmund, 1976 (Bundesarchiv, B 145 Bild-F048646-0033 \/ Wegmann, Ludwig \/ CC-BY-SA 3.0)\" width=\"686\" height=\"505\" srcset=\"https:\/\/www.schiebener.net\/wordpress\/wp-content\/uploads\/2015\/11\/helmutschmidt.jpg 686w, https:\/\/www.schiebener.net\/wordpress\/wp-content\/uploads\/2015\/11\/helmutschmidt-300x221.jpg 300w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-33929\" class=\"wp-caption-text\">Helmut Schmidt auf einem Parteitag der SPD in Dortmund, 1976 (Bundesarchiv, B 145 Bild-F048646-0033 \/ Wegmann, Ludwig \/ CC-BY-SA 3.0)<\/figcaption><\/figure>\n<p><strong>In einer fl\u00fcchtigen Minute hatte ich im Gr\u00fcndungsjahr des Blogs einen <a href=\"http:\/\/www.schiebener.net\/wordpress\/langenhorn-und-helmut-schmidt\/\" target=\"_blank\">unwichtigen Blog-Beitrag<\/a> verfasst, in dem auch Helmut Schmidt erw\u00e4hnt wurde.<\/strong><\/p>\n<p>Der Artikel entwickelte dann im Laufe der Zeit ein makaberes Eigenleben. Sobald Helmut Schmidt erkrankte, schnellte die Zahl der Zugriffe in eine durch den Inhalt des Beitrags nicht zu rechtfertigende H\u00f6he.<\/p>\n<p>Selbst als der <a href=\"http:\/\/www.taz.de\/1\/archiv\/print-archiv\/printressorts\/digi-artikel\/?ressort=ku&amp;dig=2008%2F12%2F23%2Fa0030&amp;cHash=71f4a3246cadbe7a2f1db5fcd8a0c764\" target=\"_blank\">Link zum lesenswerten Artikel von Daniel Wiese \u00fcber Helmut Schmidt<\/a> und sein (Nicht)Leben im Arbeiterstadtteil Langenhorn kaputt war, setzte sich das Ph\u00e4nomen fort.<\/p>\n<p>Den Beitrag in der taz vom Dezember 2008 habe ich <a href=\"http:\/\/www.taz.de\/1\/archiv\/print-archiv\/printressorts\/digi-artikel\/?ressort=ku&amp;dig=2008%2F12%2F23%2Fa0030&amp;cHash=71f4a3246cadbe7a2f1db5fcd8a0c764\" target=\"_blank\">inzwischen wiedergefunden<\/a>.<\/p>\n<p>Gestern und heute ist der Seismograph hoch ausgeschlagen. Helmut Schmidt ist tot. Seit ein paar Stunden \u00fcberfliege ich die Nachrufe auf den ehemaligen Kanzler der Bundesrepublik Deutschland.<\/p>\n<p>Der Sozialdemokrat Werner Jurga kommt mit seinem pers\u00f6nlichen Nachruf meinem Empfinden der damaligen Zeit recht nah. Lest seine Gedanken, wenn euch die Begriffe &#8222;bleierne Zeit&#8220; und &#8222;NATO-Doppelbeschluss&#8220; etwas sagen, sonst auch:<\/p>\n<blockquote><p>10. November 2015. Helmut Schmidt ist heute im Alter von 96 Jahren gestorben. Nein, ich war kein Helmut-Schmidt-Fan. Ich war gegen ihn und seine Politik&#8230; &#8211; und hatte mir dabei zugleich etwas vorgemacht&#8230; <a href=\"http:\/\/jurga.de\/662.html\" target=\"_blank\">Werner Jurga mit einem Nachruf<\/a><\/p><\/blockquote>\n<p>Der andere Beitrag, den ich mit Interesse gelesen habe, sch\u00e4tzt die politische Person Schmidt aus der Sicht des liberalen B\u00fcrgertums der USA ein. Er ist <a href=\"http:\/\/www.npr.org\/sections\/thetwo-way\/2015\/11\/10\/455479658\/helmut-schmidt-who-led-west-germany-s-economic-gains-dies?utm_source=twitter.com&amp;utm_campaign=npr&amp;utm_medium=social&amp;utm_term=nprnews\" target=\"_blank\">bei NPR (National Puplic Radio) erschienen<\/a>.<\/p>\n<p>Eine interessante Schilderung dort:<\/p>\n<blockquote><p>&#8222;Schmidt was brought to the stage in a wheelchair. And in a loud voice, he rebuked the current leaders, saying anyone who considers his own nation more important than common Europe damages the fundamental interests of his own country. And in a clear reference to Greece, he said the strongest must help the weak. And he reminded his successor that after World War II, Germany&#8217;s debt was also restructured.&#8220;<\/p><\/blockquote>\n<p>Bitte zweimal lesen, \u00fcbersetzen, wiederum zweimal lesen, ausdrucken und \u00fcber das politische Bett h\u00e4ngen &#8230;<\/p>\n<p>R.I.P. <a href=\"https:\/\/de.wikipedia.org\/wiki\/Helmut_Schmidt\" target=\"_blank\">Helmut Schmidt<\/a> (* 23. Dezember 1918 in Hamburg; \u2020 10. November 2015 ebenda)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In einer fl\u00fcchtigen Minute hatte ich im Gr\u00fcndungsjahr des Blogs einen unwichtigen Blog-Beitrag verfasst, in dem auch Helmut Schmidt erw\u00e4hnt wurde. Der Artikel entwickelte dann im Laufe der Zeit ein &hellip; <a href=\"https:\/\/www.schiebener.net\/wordpress\/r-i-p-helmut-schmidt-23-dezember-1918-in-hamburg-%e2%80%a0-10-november-2015-ebenda\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eR.I.P. Helmut Schmidt (* 23. Dezember 1918 in Hamburg; \u2020 10. November 2015 ebenda)\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[533,319,6,24],"tags":[5696,301],"class_list":["post-33927","post","type-post","status-publish","format-standard","hentry","category-europa","category-geschichte","category-kalenderblatt","category-politik","tag-hamburg-langenhorn","tag-helmut-schmidt"],"_links":{"self":[{"href":"https:\/\/www.schiebener.net\/wordpress\/wp-json\/wp\/v2\/posts\/33927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schiebener.net\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schiebener.net\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schiebener.net\/wordpress\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schiebener.net\/wordpress\/wp-json\/wp\/v2\/comments?post=33927"}],"version-history":[{"count":0,"href":"https:\/\/www.schiebener.net\/wordpress\/wp-json\/wp\/v2\/posts\/33927\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.schiebener.net\/wordpress\/wp-json\/wp\/v2\/media?parent=33927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schiebener.net\/wordpress\/wp-json\/wp\/v2\/categories?post=33927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schiebener.net\/wordpress\/wp-json\/wp\/v2\/tags?post=33927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}